{"id":4613,"date":"2020-10-17T21:01:21","date_gmt":"2020-10-17T21:01:21","guid":{"rendered":"https:\/\/unismilesaude.com\/?page_id=4613"},"modified":"2020-10-17T21:03:18","modified_gmt":"2020-10-17T21:03:18","slug":"proteses-dentarias","status":"publish","type":"page","link":"https:\/\/unismilesaude.com\/index.php\/proteses-dentarias\/","title":{"rendered":"Pr\u00f3teses dent\u00e1rias"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1602967200163{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221;][vc_column]<style>.ld_fancy_heading_6a58046638b78 h2 {margin-bottom:0px !important;  } .ld_fancy_heading_6a58046638b78 .lqd-highlight-inner{height:0.275em;bottom:0px;}.ld_fancy_heading_6a58046638b78 h2 {margin-bottom:0px !important;  } <\/style><div class=\"ld-fancy-heading text-uppercase ld_fancy_heading_6a58046638b78\">\n\t<h2 class=\"lqd-highlight-underline lqd-highlight-grow-left\" data-fittext=\"true\" data-fittext-options='{\"compressor\":0.5,\"maxFontSize\":\"currentFontSize\",\"minFontSize\":\"\"}'><span class=\"ld-fh-txt\"> Pr\u00f3teses dent\u00e1rias<\/span><\/h2><\/div><style>.ld_spacer_6a58046638d61{height:15px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a58046638d61\"><span class=\"liquid_empty_space_inner\"><\/span><\/div><style>.ld_fancy_heading_6a58046638e3b h6{font-size:12px;letter-spacing:0.2em;color:rgb(63, 65, 71);}.ld_fancy_heading_6a58046638e3b h6 {margin-top:0px !important;  } .ld_fancy_heading_6a58046638e3b .lqd-highlight-inner{height:0.275em;bottom:0px;}.ld_fancy_heading_6a58046638e3b h6 {margin-top:0px !important;  } <\/style><div class=\"ld-fancy-heading text-justified text-uppercase textoalinhado2 ld_fancy_heading_6a58046638e3b\">\n\t<h6 class=\"lqd-highlight-underline lqd-highlight-grow-left\" ><span class=\"ld-fh-txt\"> As pr\u00f3teses dent\u00e1rias s\u00e3o a solu\u00e7\u00e3o para dentes com imperfei\u00e7\u00f5es, ou para a perda de dentes, restituindo o sorriso \u00e0 sua boca.\u00a0<\/span><\/h6><\/div><style>.ld_spacer_6a58046638ed6{height:28px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a58046638ed6\"><span class=\"liquid_empty_space_inner\"><\/span><\/div><style>.ld_fancy_heading_6a58046638f54 .lqd-highlight-inner{height:0.275em;bottom:0px;}<\/style><div class=\"ld-fancy-heading text-justified textoalinhado2 ld_fancy_heading_6a58046638f54\">\n\t<p class=\"lqd-highlight-underline lqd-highlight-grow-left\" ><span class=\"ld-fh-txt\"> Pequenas imperfei\u00e7\u00f5es, como dentes desalinhados, desgastados, desiguais, manchados ou com espa\u00e7amento anormal podem afetar a sua autoestima e passar uma imagem pouco favor\u00e1vel. Nestes casos, podem ser aplicadas facetas, pr\u00f3teses de espessura fina aplicadas na superf\u00edcie vis\u00edvel dos dentes, para recuperar o seu aspeto natural.<\/span><\/p><\/div><style>.ld_spacer_6a58046638fc0{height:43px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a58046638fc0\"><span class=\"liquid_empty_space_inner\"><\/span><\/div><div id=\"ld_images_group_container_6a5804663904a\" class=\"liquid-img-group-container ld_images_group_container_6a5804663904a\"  >\n\t<div class=\"liquid-img-group-inner\">\n\t\t<div id=\"ld_images_group_element_6a58046639174\" class=\"liquid-img-group-single ld_images_group_element_6a58046639174\" data-roundness=\"8\" data-reveal=\"true\" data-reveal-options='{\"direction\":\"rl\",\"bgcolor\":\"rgb(23, 37, 49)\",\"delay\":\"\"}'>\n\t\n\t\t\n\t<div class=\"liquid-img-group-img-container\">\n\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"liquid-img-container-inner\" data-parallax=\"true\" data-parallax-from='{\"translateX\":4,\"scaleX\":1.1}' data-parallax-to='{\"translateX\":0,\"scaleX\":1}' data-parallax-options='{\"overflowHidden\":false,\"easing\":\"linear\"}'>\n\t\t\t<figure ><img loading=\"lazy\" decoding=\"async\" width=\"2523\" height=\"1673\" src=\"data:image\/svg+xml;charset=utf-8,&lt;svg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1600 1061&#039;%2F&gt;\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" srcset=\"\" sizes=\"auto, (max-width: 2523px) 100vw, 2523px\" data-src=\"https:\/\/unismilesaude.com\/wp-content\/uploads\/2020\/10\/protese.jpg\" data-srcset=\"https:\/\/unismilesaude.com\/wp-content\/uploads\/2020\/10\/protese.jpg 2523w, https:\/\/unismilesaude.com\/wp-content\/uploads\/2020\/10\/protese-300x199.jpg 300w, https:\/\/unismilesaude.com\/wp-content\/uploads\/2020\/10\/protese-1024x679.jpg 1024w\" data-aspect=\"1.5080113100848\" \/><\/figure>\t\t\t\t\t<\/div><!-- \/.liquid-img-container-inner -->\n\t\t\n\t<\/div><!-- \/.liquid-img-group-content -->\n<\/div><!-- \/.liquid-img-group-single -->\n\t\n\t<\/div><!-- \/.liquid-img-group-inner -->\n<\/div><!-- \/.liquid-img-group-container --><style>.ld_spacer_6a580466574e2{height:10px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a580466574e2\"><span class=\"liquid_empty_space_inner\"><\/span><\/div><style>.ld_fancy_heading_6a580466575cd .lqd-highlight-inner{height:0.275em;bottom:0px;}<\/style><div class=\"ld-fancy-heading text-justified textoalinhado2 ld_fancy_heading_6a580466575cd\">\n\t<p class=\"lqd-highlight-underline lqd-highlight-grow-left\" ><span class=\"ld-fh-txt\"> No caso da perda de dentes, \u00e9 poss\u00edvel aplicar pr\u00f3teses, remov\u00edveis, com a mesma apar\u00eancia e fun\u00e7\u00e3o de um dente normal. Estas pr\u00f3teses podem ser h\u00edbridas \u2013\u00a0quando h\u00e1 perda total de dentes \u2013 ou semifixas \u2013 quando existe uma perda at\u00e9 12 dentes. As pr\u00f3teses s\u00e3o uma solu\u00e7\u00e3o mais econ\u00f3mica do que os implantes.<\/p>\n<p>Consulte os nossos profissionais para avaliar qual a solu\u00e7\u00e3o mais indicada para si.<\/span><\/p><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1602967200163{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4613","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/unismilesaude.com\/index.php\/wp-json\/wp\/v2\/pages\/4613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unismilesaude.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unismilesaude.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unismilesaude.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unismilesaude.com\/index.php\/wp-json\/wp\/v2\/comments?post=4613"}],"version-history":[{"count":0,"href":"https:\/\/unismilesaude.com\/index.php\/wp-json\/wp\/v2\/pages\/4613\/revisions"}],"wp:attachment":[{"href":"https:\/\/unismilesaude.com\/index.php\/wp-json\/wp\/v2\/media?parent=4613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}